{"id":21660,"date":"2023-05-24T11:31:45","date_gmt":"2023-05-24T11:31:45","guid":{"rendered":"https:\/\/esment.org\/blogs\/?p=21660"},"modified":"2025-06-24T10:59:14","modified_gmt":"2025-06-24T10:59:14","slug":"esment-infancia-recibe-una-nueva-ayuda-de-caixabank-y-fundacio-sa-nostra","status":"publish","type":"post","link":"https:\/\/esment.org\/blogs\/esment-infancia-recibe-una-nueva-ayuda-de-caixabank-y-fundacio-sa-nostra\/","title":{"rendered":"Nueva ayuda de CaixaBank y Fundaci\u00f3 Sa Nostra para favorecer la autonom\u00eda de menores de 6 a 16 a\u00f1os"},"content":{"rendered":"<p>Esment Infancia ha recibido una subvenci\u00f3n de CaixaBank y Fundaci\u00f3 Sa Nostra por valor de 6.000 euros, que se destinar\u00e1 a favorecer y promocionar la autonom\u00eda de menores con necesidades de apoyo en edades comprendidas entre los 6 y los 16 a\u00f1os.<\/p>\n<p>Esta ayuda, que se concede por cuarto a\u00f1o consecutivo a la organizaci\u00f3n, se volver\u00e1 a destinar, \u00edntegramente, a las trece familias que actualmente forman parte de este servicio privado. Sin embargo, el objetivo de la entidad para finales de a\u00f1o es poder prestar este servicio a un total de 30 familias.<\/p>\n<p>El proyecto de promoci\u00f3n de la autonom\u00eda de las personas es un servicio que ofrece la organizaci\u00f3n desde el \u00e1rea de Infancia para ni\u00f1os y ni\u00f1as de 6 a 16 a\u00f1os, y que tiene como objetivo favorecer el desarrollo de un derecho fundamental que permite a todas las personas poder mejorar su calidad de vida.<\/p>\n<p>A trav\u00e9s de la Convocatoria de Acci\u00f3n Social 2023, Caixabank y Fundaci\u00f3 Sa Nostra ofrecen ayudas por valor de 150.000 euros a entidades privadas sin \u00e1nimo de lucro que desarrollan su actividad en las islas y cuyos proyectos est\u00e1n centrados en el fomento del empleo y la orientaci\u00f3n ocupacional, el desarrollo local, la inclusi\u00f3n social, y la atenci\u00f3n a la dependencia y accesibilidad.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-medium wp-image-21771\" src=\"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2023\/05\/thumbnail_Logo-negativo-300x110.jpg\" alt=\"\" width=\"300\" height=\"110\" srcset=\"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2023\/05\/thumbnail_Logo-negativo-300x110.jpg 300w, https:\/\/esment.org\/blogs\/wp-content\/uploads\/2023\/05\/thumbnail_Logo-negativo.jpg 579w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img decoding=\"async\" class=\"alignnone size-medium wp-image-21773\" src=\"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2023\/05\/Logo-CaixaBank-300x90.jpg\" alt=\"\" width=\"300\" height=\"90\" srcset=\"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2023\/05\/Logo-CaixaBank-300x90.jpg 300w, https:\/\/esment.org\/blogs\/wp-content\/uploads\/2023\/05\/Logo-CaixaBank-1024x306.jpg 1024w, https:\/\/esment.org\/blogs\/wp-content\/uploads\/2023\/05\/Logo-CaixaBank-768x229.jpg 768w, https:\/\/esment.org\/blogs\/wp-content\/uploads\/2023\/05\/Logo-CaixaBank-1536x459.jpg 1536w, https:\/\/esment.org\/blogs\/wp-content\/uploads\/2023\/05\/Logo-CaixaBank-2048x612.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esment Infancia ha recibido una subvenci\u00f3n de CaixaBank y Fundaci\u00f3 Sa Nostra por valor de 6.000 euros, que se destinar\u00e1 a favorecer y promocionar la autonom\u00eda de menores con necesidades de apoyo en edades comprendidas entre los 6 y los 16 a\u00f1os. Esta ayuda, que se concede por cuarto a\u00f1o consecutivo a la organizaci\u00f3n, se [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[1859,1866,1244],"class_list":["post-21660","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-caixabank","tag-fundacio-sanostra","tag-infancia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nueva ayuda de CaixaBank y Fundaci\u00f3 Sa Nostra para favorecer la autonom\u00eda de menores de 6 a 16 a\u00f1os - Blog Comunidad Esment<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/esment.org\/blogs\/esment-infancia-recibe-una-nueva-ayuda-de-caixabank-y-fundacio-sa-nostra\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nueva ayuda de CaixaBank y Fundaci\u00f3 Sa Nostra para favorecer la autonom\u00eda de menores de 6 a 16 a\u00f1os - Blog Comunidad Esment\" \/>\n<meta property=\"og:description\" content=\"Esment Infancia ha recibido una subvenci\u00f3n de CaixaBank y Fundaci\u00f3 Sa Nostra por valor de 6.000 euros, que se destinar\u00e1 a favorecer y promocionar la autonom\u00eda de menores con necesidades de apoyo en edades comprendidas entre los 6 y los 16 a\u00f1os. Esta ayuda, que se concede por cuarto a\u00f1o consecutivo a la organizaci\u00f3n, se [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/esment.org\/blogs\/esment-infancia-recibe-una-nueva-ayuda-de-caixabank-y-fundacio-sa-nostra\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Comunidad Esment\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-24T11:31:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-24T10:59:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2023\/05\/thumbnail_Logo-negativo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"579\" \/>\n\t<meta property=\"og:image:height\" content=\"212\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yolanda Tarramera\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yolanda Tarramera\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/esment.org\/blogs\/esment-infancia-recibe-una-nueva-ayuda-de-caixabank-y-fundacio-sa-nostra\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/esment.org\/blogs\/esment-infancia-recibe-una-nueva-ayuda-de-caixabank-y-fundacio-sa-nostra\/\"},\"author\":{\"name\":\"Yolanda Tarramera\",\"@id\":\"https:\/\/esment.org\/blogs\/#\/schema\/person\/d2af4a49059695d7ca3491e0498d6b36\"},\"headline\":\"Nueva ayuda de CaixaBank y Fundaci\u00f3 Sa Nostra para favorecer la autonom\u00eda de menores de 6 a 16 a\u00f1os\",\"datePublished\":\"2023-05-24T11:31:45+00:00\",\"dateModified\":\"2025-06-24T10:59:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/esment.org\/blogs\/esment-infancia-recibe-una-nueva-ayuda-de-caixabank-y-fundacio-sa-nostra\/\"},\"wordCount\":241,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/esment.org\/blogs\/#organization\"},\"image\":{\"@id\":\"https:\/\/esment.org\/blogs\/esment-infancia-recibe-una-nueva-ayuda-de-caixabank-y-fundacio-sa-nostra\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2023\/05\/thumbnail_Logo-negativo-300x110.jpg\",\"keywords\":[\"Caixabank\",\"Fundaci\u00f3 SaNostra\",\"infancia\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/esment.org\/blogs\/esment-infancia-recibe-una-nueva-ayuda-de-caixabank-y-fundacio-sa-nostra\/\",\"url\":\"https:\/\/esment.org\/blogs\/esment-infancia-recibe-una-nueva-ayuda-de-caixabank-y-fundacio-sa-nostra\/\",\"name\":\"Nueva ayuda de CaixaBank y Fundaci\u00f3 Sa Nostra para favorecer la autonom\u00eda de menores de 6 a 16 a\u00f1os - Blog Comunidad Esment\",\"isPartOf\":{\"@id\":\"https:\/\/esment.org\/blogs\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/esment.org\/blogs\/esment-infancia-recibe-una-nueva-ayuda-de-caixabank-y-fundacio-sa-nostra\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/esment.org\/blogs\/esment-infancia-recibe-una-nueva-ayuda-de-caixabank-y-fundacio-sa-nostra\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2023\/05\/thumbnail_Logo-negativo-300x110.jpg\",\"datePublished\":\"2023-05-24T11:31:45+00:00\",\"dateModified\":\"2025-06-24T10:59:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/esment.org\/blogs\/esment-infancia-recibe-una-nueva-ayuda-de-caixabank-y-fundacio-sa-nostra\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/esment.org\/blogs\/esment-infancia-recibe-una-nueva-ayuda-de-caixabank-y-fundacio-sa-nostra\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/esment.org\/blogs\/esment-infancia-recibe-una-nueva-ayuda-de-caixabank-y-fundacio-sa-nostra\/#primaryimage\",\"url\":\"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2023\/05\/thumbnail_Logo-negativo.jpg\",\"contentUrl\":\"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2023\/05\/thumbnail_Logo-negativo.jpg\",\"width\":579,\"height\":212},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/esment.org\/blogs\/esment-infancia-recibe-una-nueva-ayuda-de-caixabank-y-fundacio-sa-nostra\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/esment.org\/blogs\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nueva ayuda de CaixaBank y Fundaci\u00f3 Sa Nostra para favorecer la autonom\u00eda de menores de 6 a 16 a\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/esment.org\/blogs\/#website\",\"url\":\"https:\/\/esment.org\/blogs\/\",\"name\":\"Blog Comunidad Esment\",\"description\":\"Blogs de Esment\",\"publisher\":{\"@id\":\"https:\/\/esment.org\/blogs\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/esment.org\/blogs\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/esment.org\/blogs\/#organization\",\"name\":\"Blog Comunidad Esment\",\"url\":\"https:\/\/esment.org\/blogs\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/esment.org\/blogs\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2020\/10\/logo-header.svg\",\"contentUrl\":\"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2020\/10\/logo-header.svg\",\"caption\":\"Blog Comunidad Esment\"},\"image\":{\"@id\":\"https:\/\/esment.org\/blogs\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/esment.org\/blogs\/#\/schema\/person\/d2af4a49059695d7ca3491e0498d6b36\",\"name\":\"Yolanda Tarramera\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/esment.org\/blogs\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c93060ec77db68f5fefd782408bed5a5005bb0b119c5ece6cdbf5ad8631c6e5b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c93060ec77db68f5fefd782408bed5a5005bb0b119c5ece6cdbf5ad8631c6e5b?s=96&d=mm&r=g\",\"caption\":\"Yolanda Tarramera\"},\"url\":\"https:\/\/esment.org\/blogs\/author\/yolanda-tarramera\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nueva ayuda de CaixaBank y Fundaci\u00f3 Sa Nostra para favorecer la autonom\u00eda de menores de 6 a 16 a\u00f1os - Blog Comunidad Esment","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/esment.org\/blogs\/esment-infancia-recibe-una-nueva-ayuda-de-caixabank-y-fundacio-sa-nostra\/","og_locale":"es_ES","og_type":"article","og_title":"Nueva ayuda de CaixaBank y Fundaci\u00f3 Sa Nostra para favorecer la autonom\u00eda de menores de 6 a 16 a\u00f1os - Blog Comunidad Esment","og_description":"Esment Infancia ha recibido una subvenci\u00f3n de CaixaBank y Fundaci\u00f3 Sa Nostra por valor de 6.000 euros, que se destinar\u00e1 a favorecer y promocionar la autonom\u00eda de menores con necesidades de apoyo en edades comprendidas entre los 6 y los 16 a\u00f1os. Esta ayuda, que se concede por cuarto a\u00f1o consecutivo a la organizaci\u00f3n, se [&hellip;]","og_url":"https:\/\/esment.org\/blogs\/esment-infancia-recibe-una-nueva-ayuda-de-caixabank-y-fundacio-sa-nostra\/","og_site_name":"Blog Comunidad Esment","article_published_time":"2023-05-24T11:31:45+00:00","article_modified_time":"2025-06-24T10:59:14+00:00","og_image":[{"width":579,"height":212,"url":"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2023\/05\/thumbnail_Logo-negativo.jpg","type":"image\/jpeg"}],"author":"Yolanda Tarramera","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Yolanda Tarramera","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/esment.org\/blogs\/esment-infancia-recibe-una-nueva-ayuda-de-caixabank-y-fundacio-sa-nostra\/#article","isPartOf":{"@id":"https:\/\/esment.org\/blogs\/esment-infancia-recibe-una-nueva-ayuda-de-caixabank-y-fundacio-sa-nostra\/"},"author":{"name":"Yolanda Tarramera","@id":"https:\/\/esment.org\/blogs\/#\/schema\/person\/d2af4a49059695d7ca3491e0498d6b36"},"headline":"Nueva ayuda de CaixaBank y Fundaci\u00f3 Sa Nostra para favorecer la autonom\u00eda de menores de 6 a 16 a\u00f1os","datePublished":"2023-05-24T11:31:45+00:00","dateModified":"2025-06-24T10:59:14+00:00","mainEntityOfPage":{"@id":"https:\/\/esment.org\/blogs\/esment-infancia-recibe-una-nueva-ayuda-de-caixabank-y-fundacio-sa-nostra\/"},"wordCount":241,"commentCount":0,"publisher":{"@id":"https:\/\/esment.org\/blogs\/#organization"},"image":{"@id":"https:\/\/esment.org\/blogs\/esment-infancia-recibe-una-nueva-ayuda-de-caixabank-y-fundacio-sa-nostra\/#primaryimage"},"thumbnailUrl":"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2023\/05\/thumbnail_Logo-negativo-300x110.jpg","keywords":["Caixabank","Fundaci\u00f3 SaNostra","infancia"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/esment.org\/blogs\/esment-infancia-recibe-una-nueva-ayuda-de-caixabank-y-fundacio-sa-nostra\/","url":"https:\/\/esment.org\/blogs\/esment-infancia-recibe-una-nueva-ayuda-de-caixabank-y-fundacio-sa-nostra\/","name":"Nueva ayuda de CaixaBank y Fundaci\u00f3 Sa Nostra para favorecer la autonom\u00eda de menores de 6 a 16 a\u00f1os - Blog Comunidad Esment","isPartOf":{"@id":"https:\/\/esment.org\/blogs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/esment.org\/blogs\/esment-infancia-recibe-una-nueva-ayuda-de-caixabank-y-fundacio-sa-nostra\/#primaryimage"},"image":{"@id":"https:\/\/esment.org\/blogs\/esment-infancia-recibe-una-nueva-ayuda-de-caixabank-y-fundacio-sa-nostra\/#primaryimage"},"thumbnailUrl":"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2023\/05\/thumbnail_Logo-negativo-300x110.jpg","datePublished":"2023-05-24T11:31:45+00:00","dateModified":"2025-06-24T10:59:14+00:00","breadcrumb":{"@id":"https:\/\/esment.org\/blogs\/esment-infancia-recibe-una-nueva-ayuda-de-caixabank-y-fundacio-sa-nostra\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/esment.org\/blogs\/esment-infancia-recibe-una-nueva-ayuda-de-caixabank-y-fundacio-sa-nostra\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/esment.org\/blogs\/esment-infancia-recibe-una-nueva-ayuda-de-caixabank-y-fundacio-sa-nostra\/#primaryimage","url":"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2023\/05\/thumbnail_Logo-negativo.jpg","contentUrl":"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2023\/05\/thumbnail_Logo-negativo.jpg","width":579,"height":212},{"@type":"BreadcrumbList","@id":"https:\/\/esment.org\/blogs\/esment-infancia-recibe-una-nueva-ayuda-de-caixabank-y-fundacio-sa-nostra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/esment.org\/blogs\/"},{"@type":"ListItem","position":2,"name":"Nueva ayuda de CaixaBank y Fundaci\u00f3 Sa Nostra para favorecer la autonom\u00eda de menores de 6 a 16 a\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/esment.org\/blogs\/#website","url":"https:\/\/esment.org\/blogs\/","name":"Blog Comunidad Esment","description":"Blogs de Esment","publisher":{"@id":"https:\/\/esment.org\/blogs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/esment.org\/blogs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/esment.org\/blogs\/#organization","name":"Blog Comunidad Esment","url":"https:\/\/esment.org\/blogs\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/esment.org\/blogs\/#\/schema\/logo\/image\/","url":"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2020\/10\/logo-header.svg","contentUrl":"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2020\/10\/logo-header.svg","caption":"Blog Comunidad Esment"},"image":{"@id":"https:\/\/esment.org\/blogs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/esment.org\/blogs\/#\/schema\/person\/d2af4a49059695d7ca3491e0498d6b36","name":"Yolanda Tarramera","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/esment.org\/blogs\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c93060ec77db68f5fefd782408bed5a5005bb0b119c5ece6cdbf5ad8631c6e5b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c93060ec77db68f5fefd782408bed5a5005bb0b119c5ece6cdbf5ad8631c6e5b?s=96&d=mm&r=g","caption":"Yolanda Tarramera"},"url":"https:\/\/esment.org\/blogs\/author\/yolanda-tarramera\/"}]}},"_links":{"self":[{"href":"https:\/\/esment.org\/blogs\/wp-json\/wp\/v2\/posts\/21660","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esment.org\/blogs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esment.org\/blogs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esment.org\/blogs\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/esment.org\/blogs\/wp-json\/wp\/v2\/comments?post=21660"}],"version-history":[{"count":7,"href":"https:\/\/esment.org\/blogs\/wp-json\/wp\/v2\/posts\/21660\/revisions"}],"predecessor-version":[{"id":21775,"href":"https:\/\/esment.org\/blogs\/wp-json\/wp\/v2\/posts\/21660\/revisions\/21775"}],"wp:attachment":[{"href":"https:\/\/esment.org\/blogs\/wp-json\/wp\/v2\/media?parent=21660"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esment.org\/blogs\/wp-json\/wp\/v2\/categories?post=21660"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esment.org\/blogs\/wp-json\/wp\/v2\/tags?post=21660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}