{"id":21628,"date":"2023-05-19T09:16:48","date_gmt":"2023-05-19T09:16:48","guid":{"rendered":"https:\/\/esment.org\/blogs\/?p=21628"},"modified":"2023-05-19T10:46:41","modified_gmt":"2023-05-19T10:46:41","slug":"a-toda-maquina-en-imprenta","status":"publish","type":"post","link":"https:\/\/esment.org\/blogs\/a-toda-maquina-en-imprenta\/","title":{"rendered":"\u00a1A toda m\u00e1quina en Imprenta!"},"content":{"rendered":"<p>Las m\u00e1quinas de impresi\u00f3n echan humo estos d\u00edas en las instalaciones de Esment Imprenta. A los encargos habituales, se han sumado las impresiones de las papeletas y sobres electorales que se distribuir\u00e1n por los colegios de cara a las pr\u00f3ximas elecciones del 28 de mayo. Se repartir\u00e1n por todas las islas y los primeros pal\u00e9s ya salieron de las instalaciones hace d\u00edas.<\/p>\n<p>Un trabajo a contra reloj que ser\u00eda imposible realizar sin el esfuerzo y trabajo de las m\u00e1s de 100 personas que controlan, organizan y gestionan la extraordinaria cadena de producci\u00f3n que hay impl\u00edcita en esta actividad.\u00a0 En este caso, las personas del servicio ocupacional se han sumado a la cadena de manipulados para contribuir a conseguir un objetivo satisfactorio para todo el equipo.<\/p>\n<p>Pero esta no es, ni probablemente ser\u00e1, la \u00faltima vez que queda demostrada la extraordinaria capacidad de respuesta del equipo de personas que trabajan y participan en esta actividad. Hace apenas unas semanas, estas mismas personas se encontraron ante el reto de realizar un trabajo de ensobrado a mano para el SOIB, en tiempo r\u00e9cord. Por un problema log\u00edstico ajeno a Esment Imprenta, el equipo se vio obligado a ensobrar a mano 100.000 sobres. Solo dispon\u00edan de tres d\u00edas para hacerlo si quer\u00edan cumplir con la entrega. Al equipo de Imprenta se sumaron otros trabajadores de la casa, en total cerca de 300 personas participaron en el ensobrado. El SOIB recibi\u00f3 su encargo y las personas, la gran satisfacci\u00f3n de haber logrado lo que parec\u00eda imposible de conseguir.<\/p>\n<p>Enhorabuena a todo el equipo de Esment Imprenta.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-large wp-image-21633\" src=\"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2023\/05\/Imprenta3-1024x768.jpg\" alt=\"\" width=\"800\" height=\"600\" srcset=\"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2023\/05\/Imprenta3-1024x768.jpg 1024w, https:\/\/esment.org\/blogs\/wp-content\/uploads\/2023\/05\/Imprenta3-300x225.jpg 300w, https:\/\/esment.org\/blogs\/wp-content\/uploads\/2023\/05\/Imprenta3-768x576.jpg 768w, https:\/\/esment.org\/blogs\/wp-content\/uploads\/2023\/05\/Imprenta3-1536x1152.jpg 1536w, https:\/\/esment.org\/blogs\/wp-content\/uploads\/2023\/05\/Imprenta3.jpg 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las m\u00e1quinas de impresi\u00f3n echan humo estos d\u00edas en las instalaciones de Esment Imprenta. A los encargos habituales, se han sumado las impresiones de las papeletas y sobres electorales que se distribuir\u00e1n por los colegios de cara a las pr\u00f3ximas elecciones del 28 de mayo. Se repartir\u00e1n por todas las islas y los primeros pal\u00e9s [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":21630,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[1047,1850,381,96,1341,1849],"class_list":["post-21628","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria","tag-actividad","tag-elecciones","tag-formacion-dual","tag-imprenta-2","tag-insercion-sociolaboral","tag-personas-en-ocupacion"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00a1A toda m\u00e1quina en Imprenta! - Blog Comunidad Esment<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/esment.org\/blogs\/a-toda-maquina-en-imprenta\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1A toda m\u00e1quina en Imprenta! - Blog Comunidad Esment\" \/>\n<meta property=\"og:description\" content=\"Las m\u00e1quinas de impresi\u00f3n echan humo estos d\u00edas en las instalaciones de Esment Imprenta. A los encargos habituales, se han sumado las impresiones de las papeletas y sobres electorales que se distribuir\u00e1n por los colegios de cara a las pr\u00f3ximas elecciones del 28 de mayo. Se repartir\u00e1n por todas las islas y los primeros pal\u00e9s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/esment.org\/blogs\/a-toda-maquina-en-imprenta\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Comunidad Esment\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-19T09:16:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-19T10:46:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2023\/05\/Diseno-sin-titulo-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yolanda Tarramera\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yolanda Tarramera\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/esment.org\/blogs\/a-toda-maquina-en-imprenta\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/esment.org\/blogs\/a-toda-maquina-en-imprenta\/\"},\"author\":{\"name\":\"Yolanda Tarramera\",\"@id\":\"https:\/\/esment.org\/blogs\/#\/schema\/person\/d2af4a49059695d7ca3491e0498d6b36\"},\"headline\":\"\u00a1A toda m\u00e1quina en Imprenta!\",\"datePublished\":\"2023-05-19T09:16:48+00:00\",\"dateModified\":\"2023-05-19T10:46:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/esment.org\/blogs\/a-toda-maquina-en-imprenta\/\"},\"wordCount\":282,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/esment.org\/blogs\/#organization\"},\"image\":{\"@id\":\"https:\/\/esment.org\/blogs\/a-toda-maquina-en-imprenta\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2023\/05\/Diseno-sin-titulo-1.jpg\",\"keywords\":[\"actividad\",\"elecciones\",\"formaci\u00f3n dual\",\"imprenta\",\"inserci\u00f3n sociolaboral\",\"personas en ocupaci\u00f3n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/esment.org\/blogs\/a-toda-maquina-en-imprenta\/\",\"url\":\"https:\/\/esment.org\/blogs\/a-toda-maquina-en-imprenta\/\",\"name\":\"\u00a1A toda m\u00e1quina en Imprenta! - Blog Comunidad Esment\",\"isPartOf\":{\"@id\":\"https:\/\/esment.org\/blogs\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/esment.org\/blogs\/a-toda-maquina-en-imprenta\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/esment.org\/blogs\/a-toda-maquina-en-imprenta\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2023\/05\/Diseno-sin-titulo-1.jpg\",\"datePublished\":\"2023-05-19T09:16:48+00:00\",\"dateModified\":\"2023-05-19T10:46:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/esment.org\/blogs\/a-toda-maquina-en-imprenta\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/esment.org\/blogs\/a-toda-maquina-en-imprenta\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/esment.org\/blogs\/a-toda-maquina-en-imprenta\/#primaryimage\",\"url\":\"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2023\/05\/Diseno-sin-titulo-1.jpg\",\"contentUrl\":\"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2023\/05\/Diseno-sin-titulo-1.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/esment.org\/blogs\/a-toda-maquina-en-imprenta\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/esment.org\/blogs\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a1A toda m\u00e1quina en Imprenta!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/esment.org\/blogs\/#website\",\"url\":\"https:\/\/esment.org\/blogs\/\",\"name\":\"Blog Comunidad Esment\",\"description\":\"Blogs de Esment\",\"publisher\":{\"@id\":\"https:\/\/esment.org\/blogs\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/esment.org\/blogs\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/esment.org\/blogs\/#organization\",\"name\":\"Blog Comunidad Esment\",\"url\":\"https:\/\/esment.org\/blogs\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/esment.org\/blogs\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2020\/10\/logo-header.svg\",\"contentUrl\":\"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2020\/10\/logo-header.svg\",\"caption\":\"Blog Comunidad Esment\"},\"image\":{\"@id\":\"https:\/\/esment.org\/blogs\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/esment.org\/blogs\/#\/schema\/person\/d2af4a49059695d7ca3491e0498d6b36\",\"name\":\"Yolanda Tarramera\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/esment.org\/blogs\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c93060ec77db68f5fefd782408bed5a5005bb0b119c5ece6cdbf5ad8631c6e5b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c93060ec77db68f5fefd782408bed5a5005bb0b119c5ece6cdbf5ad8631c6e5b?s=96&d=mm&r=g\",\"caption\":\"Yolanda Tarramera\"},\"url\":\"https:\/\/esment.org\/blogs\/author\/yolanda-tarramera\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1A toda m\u00e1quina en Imprenta! - Blog Comunidad Esment","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/esment.org\/blogs\/a-toda-maquina-en-imprenta\/","og_locale":"es_ES","og_type":"article","og_title":"\u00a1A toda m\u00e1quina en Imprenta! - Blog Comunidad Esment","og_description":"Las m\u00e1quinas de impresi\u00f3n echan humo estos d\u00edas en las instalaciones de Esment Imprenta. A los encargos habituales, se han sumado las impresiones de las papeletas y sobres electorales que se distribuir\u00e1n por los colegios de cara a las pr\u00f3ximas elecciones del 28 de mayo. Se repartir\u00e1n por todas las islas y los primeros pal\u00e9s [&hellip;]","og_url":"https:\/\/esment.org\/blogs\/a-toda-maquina-en-imprenta\/","og_site_name":"Blog Comunidad Esment","article_published_time":"2023-05-19T09:16:48+00:00","article_modified_time":"2023-05-19T10:46:41+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2023\/05\/Diseno-sin-titulo-1.jpg","type":"image\/jpeg"}],"author":"Yolanda Tarramera","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Yolanda Tarramera","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/esment.org\/blogs\/a-toda-maquina-en-imprenta\/#article","isPartOf":{"@id":"https:\/\/esment.org\/blogs\/a-toda-maquina-en-imprenta\/"},"author":{"name":"Yolanda Tarramera","@id":"https:\/\/esment.org\/blogs\/#\/schema\/person\/d2af4a49059695d7ca3491e0498d6b36"},"headline":"\u00a1A toda m\u00e1quina en Imprenta!","datePublished":"2023-05-19T09:16:48+00:00","dateModified":"2023-05-19T10:46:41+00:00","mainEntityOfPage":{"@id":"https:\/\/esment.org\/blogs\/a-toda-maquina-en-imprenta\/"},"wordCount":282,"commentCount":0,"publisher":{"@id":"https:\/\/esment.org\/blogs\/#organization"},"image":{"@id":"https:\/\/esment.org\/blogs\/a-toda-maquina-en-imprenta\/#primaryimage"},"thumbnailUrl":"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2023\/05\/Diseno-sin-titulo-1.jpg","keywords":["actividad","elecciones","formaci\u00f3n dual","imprenta","inserci\u00f3n sociolaboral","personas en ocupaci\u00f3n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/esment.org\/blogs\/a-toda-maquina-en-imprenta\/","url":"https:\/\/esment.org\/blogs\/a-toda-maquina-en-imprenta\/","name":"\u00a1A toda m\u00e1quina en Imprenta! - Blog Comunidad Esment","isPartOf":{"@id":"https:\/\/esment.org\/blogs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/esment.org\/blogs\/a-toda-maquina-en-imprenta\/#primaryimage"},"image":{"@id":"https:\/\/esment.org\/blogs\/a-toda-maquina-en-imprenta\/#primaryimage"},"thumbnailUrl":"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2023\/05\/Diseno-sin-titulo-1.jpg","datePublished":"2023-05-19T09:16:48+00:00","dateModified":"2023-05-19T10:46:41+00:00","breadcrumb":{"@id":"https:\/\/esment.org\/blogs\/a-toda-maquina-en-imprenta\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/esment.org\/blogs\/a-toda-maquina-en-imprenta\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/esment.org\/blogs\/a-toda-maquina-en-imprenta\/#primaryimage","url":"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2023\/05\/Diseno-sin-titulo-1.jpg","contentUrl":"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2023\/05\/Diseno-sin-titulo-1.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/esment.org\/blogs\/a-toda-maquina-en-imprenta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/esment.org\/blogs\/"},{"@type":"ListItem","position":2,"name":"\u00a1A toda m\u00e1quina en Imprenta!"}]},{"@type":"WebSite","@id":"https:\/\/esment.org\/blogs\/#website","url":"https:\/\/esment.org\/blogs\/","name":"Blog Comunidad Esment","description":"Blogs de Esment","publisher":{"@id":"https:\/\/esment.org\/blogs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/esment.org\/blogs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/esment.org\/blogs\/#organization","name":"Blog Comunidad Esment","url":"https:\/\/esment.org\/blogs\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/esment.org\/blogs\/#\/schema\/logo\/image\/","url":"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2020\/10\/logo-header.svg","contentUrl":"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2020\/10\/logo-header.svg","caption":"Blog Comunidad Esment"},"image":{"@id":"https:\/\/esment.org\/blogs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/esment.org\/blogs\/#\/schema\/person\/d2af4a49059695d7ca3491e0498d6b36","name":"Yolanda Tarramera","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/esment.org\/blogs\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c93060ec77db68f5fefd782408bed5a5005bb0b119c5ece6cdbf5ad8631c6e5b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c93060ec77db68f5fefd782408bed5a5005bb0b119c5ece6cdbf5ad8631c6e5b?s=96&d=mm&r=g","caption":"Yolanda Tarramera"},"url":"https:\/\/esment.org\/blogs\/author\/yolanda-tarramera\/"}]}},"_links":{"self":[{"href":"https:\/\/esment.org\/blogs\/wp-json\/wp\/v2\/posts\/21628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esment.org\/blogs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esment.org\/blogs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esment.org\/blogs\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/esment.org\/blogs\/wp-json\/wp\/v2\/comments?post=21628"}],"version-history":[{"count":8,"href":"https:\/\/esment.org\/blogs\/wp-json\/wp\/v2\/posts\/21628\/revisions"}],"predecessor-version":[{"id":21642,"href":"https:\/\/esment.org\/blogs\/wp-json\/wp\/v2\/posts\/21628\/revisions\/21642"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esment.org\/blogs\/wp-json\/wp\/v2\/media\/21630"}],"wp:attachment":[{"href":"https:\/\/esment.org\/blogs\/wp-json\/wp\/v2\/media?parent=21628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esment.org\/blogs\/wp-json\/wp\/v2\/categories?post=21628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esment.org\/blogs\/wp-json\/wp\/v2\/tags?post=21628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}