{"id":17989,"date":"2021-02-24T18:01:58","date_gmt":"2021-02-24T18:01:58","guid":{"rendered":"https:\/\/esment.org\/blogs\/?p=17989"},"modified":"2021-11-11T08:54:52","modified_gmt":"2021-11-11T08:54:52","slug":"participamos-en-el-proyecto-create-future","status":"publish","type":"post","link":"https:\/\/esment.org\/blogs\/participamos-en-el-proyecto-create-future\/","title":{"rendered":"Participamos en el proyecto CREATE FUTURE"},"content":{"rendered":"\r\n<p>El proyecto CREATE FUTURE &#8211; Creating Support Models for Participation in Future Work Life (creando modelos de apoyo para la participaci\u00f3n futura en la vida laboral) es un proyecto financiado por Erasmus + que se centra en la creaci\u00f3n de herramientas para orientadores y profesionales que prestan apoyos a personas que pertenecen a colectivos vulnerables. Estas herramientas, basadas en los \u00faltimos modelos de orientaci\u00f3n, permiten un mejor acompa\u00f1amiento y tutorizaci\u00f3n de las personas con necesidades de apoyo durante sus procesos de inserci\u00f3n.<\/p>\r\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-18522\" src=\"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2021\/02\/CreateFuture_logo_final-300x265.png\" alt=\"\" width=\"300\" height=\"265\" srcset=\"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2021\/02\/CreateFuture_logo_final-300x265.png 300w, https:\/\/esment.org\/blogs\/wp-content\/uploads\/2021\/02\/CreateFuture_logo_final.png 727w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\r\n<p>En el <a href=\"https:\/\/createfutureerasmus.blogspot.com\/\">BLOG GLOBAL del proyecto<\/a> pod\u00e9is encontrar m\u00e1s informaci\u00f3n general.<\/p>\r\n<p>&nbsp;<\/p>\r\n<p><img decoding=\"async\" class=\"alignnone wp-image-18684 size-full\" src=\"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2021\/02\/Sin-titulo.jpg\" alt=\"\" width=\"1414\" height=\"2222\" srcset=\"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2021\/02\/Sin-titulo.jpg 1414w, https:\/\/esment.org\/blogs\/wp-content\/uploads\/2021\/02\/Sin-titulo-191x300.jpg 191w, https:\/\/esment.org\/blogs\/wp-content\/uploads\/2021\/02\/Sin-titulo-652x1024.jpg 652w, https:\/\/esment.org\/blogs\/wp-content\/uploads\/2021\/02\/Sin-titulo-768x1207.jpg 768w, https:\/\/esment.org\/blogs\/wp-content\/uploads\/2021\/02\/Sin-titulo-977x1536.jpg 977w, https:\/\/esment.org\/blogs\/wp-content\/uploads\/2021\/02\/Sin-titulo-1303x2048.jpg 1303w\" sizes=\"(max-width: 1414px) 100vw, 1414px\" \/><\/p>\r\n\r\n\r\n\r\n<pre id=\"tw-target-text\" class=\"wp-block-preformatted\">\u00a0<\/pre>\r\n","protected":false},"excerpt":{"rendered":"<p>El proyecto CREATE FUTURE &#8211; Creating Support Models for Participation in Future Work Life (creando modelos de apoyo para la participaci\u00f3n futura en la vida laboral) es un proyecto financiado por Erasmus + que se centra en la creaci\u00f3n de herramientas para orientadores y profesionales que prestan apoyos a personas que pertenecen a colectivos vulnerables. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":17999,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-17989","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Participamos en el proyecto CREATE FUTURE - Blog Comunidad Esment<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/esment.org\/blogs\/participamos-en-el-proyecto-create-future\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Participamos en el proyecto CREATE FUTURE - Blog Comunidad Esment\" \/>\n<meta property=\"og:description\" content=\"El proyecto CREATE FUTURE &#8211; Creating Support Models for Participation in Future Work Life (creando modelos de apoyo para la participaci\u00f3n futura en la vida laboral) es un proyecto financiado por Erasmus + que se centra en la creaci\u00f3n de herramientas para orientadores y profesionales que prestan apoyos a personas que pertenecen a colectivos vulnerables. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/esment.org\/blogs\/participamos-en-el-proyecto-create-future\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Comunidad Esment\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-24T18:01:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-11T08:54:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2021\/02\/erasmus1-900x675-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comunicaci\u00f3\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicaci\u00f3\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/esment.org\/blogs\/participamos-en-el-proyecto-create-future\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/esment.org\/blogs\/participamos-en-el-proyecto-create-future\/\"},\"author\":{\"name\":\"Comunicaci\u00f3\",\"@id\":\"https:\/\/esment.org\/blogs\/#\/schema\/person\/bda902bc715a8b0d1184995111e1ec39\"},\"headline\":\"Participamos en el proyecto CREATE FUTURE\",\"datePublished\":\"2021-02-24T18:01:58+00:00\",\"dateModified\":\"2021-11-11T08:54:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/esment.org\/blogs\/participamos-en-el-proyecto-create-future\/\"},\"wordCount\":108,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/esment.org\/blogs\/#organization\"},\"image\":{\"@id\":\"https:\/\/esment.org\/blogs\/participamos-en-el-proyecto-create-future\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2021\/02\/erasmus1-900x675-1.jpg\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/esment.org\/blogs\/participamos-en-el-proyecto-create-future\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/esment.org\/blogs\/participamos-en-el-proyecto-create-future\/\",\"url\":\"https:\/\/esment.org\/blogs\/participamos-en-el-proyecto-create-future\/\",\"name\":\"Participamos en el proyecto CREATE FUTURE - Blog Comunidad Esment\",\"isPartOf\":{\"@id\":\"https:\/\/esment.org\/blogs\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/esment.org\/blogs\/participamos-en-el-proyecto-create-future\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/esment.org\/blogs\/participamos-en-el-proyecto-create-future\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2021\/02\/erasmus1-900x675-1.jpg\",\"datePublished\":\"2021-02-24T18:01:58+00:00\",\"dateModified\":\"2021-11-11T08:54:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/esment.org\/blogs\/participamos-en-el-proyecto-create-future\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/esment.org\/blogs\/participamos-en-el-proyecto-create-future\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/esment.org\/blogs\/participamos-en-el-proyecto-create-future\/#primaryimage\",\"url\":\"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2021\/02\/erasmus1-900x675-1.jpg\",\"contentUrl\":\"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2021\/02\/erasmus1-900x675-1.jpg\",\"width\":900,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/esment.org\/blogs\/participamos-en-el-proyecto-create-future\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/esment.org\/blogs\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Participamos en el proyecto CREATE FUTURE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/esment.org\/blogs\/#website\",\"url\":\"https:\/\/esment.org\/blogs\/\",\"name\":\"Blog Comunidad Esment\",\"description\":\"Blogs de Esment\",\"publisher\":{\"@id\":\"https:\/\/esment.org\/blogs\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/esment.org\/blogs\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/esment.org\/blogs\/#organization\",\"name\":\"Blog Comunidad Esment\",\"url\":\"https:\/\/esment.org\/blogs\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/esment.org\/blogs\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2020\/10\/logo-header.svg\",\"contentUrl\":\"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2020\/10\/logo-header.svg\",\"caption\":\"Blog Comunidad Esment\"},\"image\":{\"@id\":\"https:\/\/esment.org\/blogs\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/esment.org\/blogs\/#\/schema\/person\/bda902bc715a8b0d1184995111e1ec39\",\"name\":\"Comunicaci\u00f3\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/esment.org\/blogs\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4f968fdbd4d304fdc98812fe8d7d2a6bb4e6d324bdece016602fc6863fab2c66?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4f968fdbd4d304fdc98812fe8d7d2a6bb4e6d324bdece016602fc6863fab2c66?s=96&d=mm&r=g\",\"caption\":\"Comunicaci\u00f3\"},\"url\":\"https:\/\/esment.org\/blogs\/author\/mercemarrero\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Participamos en el proyecto CREATE FUTURE - Blog Comunidad Esment","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/esment.org\/blogs\/participamos-en-el-proyecto-create-future\/","og_locale":"es_ES","og_type":"article","og_title":"Participamos en el proyecto CREATE FUTURE - Blog Comunidad Esment","og_description":"El proyecto CREATE FUTURE &#8211; Creating Support Models for Participation in Future Work Life (creando modelos de apoyo para la participaci\u00f3n futura en la vida laboral) es un proyecto financiado por Erasmus + que se centra en la creaci\u00f3n de herramientas para orientadores y profesionales que prestan apoyos a personas que pertenecen a colectivos vulnerables. [&hellip;]","og_url":"https:\/\/esment.org\/blogs\/participamos-en-el-proyecto-create-future\/","og_site_name":"Blog Comunidad Esment","article_published_time":"2021-02-24T18:01:58+00:00","article_modified_time":"2021-11-11T08:54:52+00:00","og_image":[{"width":900,"height":675,"url":"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2021\/02\/erasmus1-900x675-1.jpg","type":"image\/jpeg"}],"author":"Comunicaci\u00f3","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Comunicaci\u00f3","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/esment.org\/blogs\/participamos-en-el-proyecto-create-future\/#article","isPartOf":{"@id":"https:\/\/esment.org\/blogs\/participamos-en-el-proyecto-create-future\/"},"author":{"name":"Comunicaci\u00f3","@id":"https:\/\/esment.org\/blogs\/#\/schema\/person\/bda902bc715a8b0d1184995111e1ec39"},"headline":"Participamos en el proyecto CREATE FUTURE","datePublished":"2021-02-24T18:01:58+00:00","dateModified":"2021-11-11T08:54:52+00:00","mainEntityOfPage":{"@id":"https:\/\/esment.org\/blogs\/participamos-en-el-proyecto-create-future\/"},"wordCount":108,"commentCount":0,"publisher":{"@id":"https:\/\/esment.org\/blogs\/#organization"},"image":{"@id":"https:\/\/esment.org\/blogs\/participamos-en-el-proyecto-create-future\/#primaryimage"},"thumbnailUrl":"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2021\/02\/erasmus1-900x675-1.jpg","inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/esment.org\/blogs\/participamos-en-el-proyecto-create-future\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/esment.org\/blogs\/participamos-en-el-proyecto-create-future\/","url":"https:\/\/esment.org\/blogs\/participamos-en-el-proyecto-create-future\/","name":"Participamos en el proyecto CREATE FUTURE - Blog Comunidad Esment","isPartOf":{"@id":"https:\/\/esment.org\/blogs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/esment.org\/blogs\/participamos-en-el-proyecto-create-future\/#primaryimage"},"image":{"@id":"https:\/\/esment.org\/blogs\/participamos-en-el-proyecto-create-future\/#primaryimage"},"thumbnailUrl":"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2021\/02\/erasmus1-900x675-1.jpg","datePublished":"2021-02-24T18:01:58+00:00","dateModified":"2021-11-11T08:54:52+00:00","breadcrumb":{"@id":"https:\/\/esment.org\/blogs\/participamos-en-el-proyecto-create-future\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/esment.org\/blogs\/participamos-en-el-proyecto-create-future\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/esment.org\/blogs\/participamos-en-el-proyecto-create-future\/#primaryimage","url":"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2021\/02\/erasmus1-900x675-1.jpg","contentUrl":"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2021\/02\/erasmus1-900x675-1.jpg","width":900,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/esment.org\/blogs\/participamos-en-el-proyecto-create-future\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/esment.org\/blogs\/"},{"@type":"ListItem","position":2,"name":"Participamos en el proyecto CREATE FUTURE"}]},{"@type":"WebSite","@id":"https:\/\/esment.org\/blogs\/#website","url":"https:\/\/esment.org\/blogs\/","name":"Blog Comunidad Esment","description":"Blogs de Esment","publisher":{"@id":"https:\/\/esment.org\/blogs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/esment.org\/blogs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/esment.org\/blogs\/#organization","name":"Blog Comunidad Esment","url":"https:\/\/esment.org\/blogs\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/esment.org\/blogs\/#\/schema\/logo\/image\/","url":"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2020\/10\/logo-header.svg","contentUrl":"https:\/\/esment.org\/blogs\/wp-content\/uploads\/2020\/10\/logo-header.svg","caption":"Blog Comunidad Esment"},"image":{"@id":"https:\/\/esment.org\/blogs\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/esment.org\/blogs\/#\/schema\/person\/bda902bc715a8b0d1184995111e1ec39","name":"Comunicaci\u00f3","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/esment.org\/blogs\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4f968fdbd4d304fdc98812fe8d7d2a6bb4e6d324bdece016602fc6863fab2c66?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f968fdbd4d304fdc98812fe8d7d2a6bb4e6d324bdece016602fc6863fab2c66?s=96&d=mm&r=g","caption":"Comunicaci\u00f3"},"url":"https:\/\/esment.org\/blogs\/author\/mercemarrero\/"}]}},"_links":{"self":[{"href":"https:\/\/esment.org\/blogs\/wp-json\/wp\/v2\/posts\/17989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esment.org\/blogs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esment.org\/blogs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esment.org\/blogs\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/esment.org\/blogs\/wp-json\/wp\/v2\/comments?post=17989"}],"version-history":[{"count":8,"href":"https:\/\/esment.org\/blogs\/wp-json\/wp\/v2\/posts\/17989\/revisions"}],"predecessor-version":[{"id":18687,"href":"https:\/\/esment.org\/blogs\/wp-json\/wp\/v2\/posts\/17989\/revisions\/18687"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esment.org\/blogs\/wp-json\/wp\/v2\/media\/17999"}],"wp:attachment":[{"href":"https:\/\/esment.org\/blogs\/wp-json\/wp\/v2\/media?parent=17989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esment.org\/blogs\/wp-json\/wp\/v2\/categories?post=17989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esment.org\/blogs\/wp-json\/wp\/v2\/tags?post=17989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}